{"id":736,"date":"2024-01-03T02:45:48","date_gmt":"2024-01-03T02:45:48","guid":{"rendered":"https:\/\/mariolealphoto.com\/?page_id=736"},"modified":"2024-05-07T21:38:09","modified_gmt":"2024-05-08T03:38:09","slug":"people","status":"publish","type":"page","link":"https:\/\/mariolealphoto.com\/es\/people\/","title":{"rendered":"personas"},"content":{"rendered":"<style>.kb-row-layout-id736_aaa214-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id736_aaa214-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id736_aaa214-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id736_aaa214-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id736_aaa214-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (min-width: 768px) and (max-width: 1024px){.kb-row-layout-id736_aaa214-20{display:none !important;}}@media all and (max-width: 767px){.kb-row-layout-id736_aaa214-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id736_aaa214-20{display:none !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id736_aaa214-20 alignnone kb-v-md-hidden kb-v-sm-hidden wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column736_cdc494-c7 > .kt-inside-inner-col,.kadence-column736_cdc494-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column736_cdc494-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column736_cdc494-c7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column736_cdc494-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column736_cdc494-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column736_cdc494-c7{position:relative;}@media all and (max-width: 1024px){.kadence-column736_cdc494-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column736_cdc494-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column736_cdc494-c7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-736_2fd7fb-0d{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-736_2fd7fb-0d .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-736_2fd7fb-0d .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-736_2fd7fb-0d .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-caption-style-bottom.kb-gallery-id-736_2fd7fb-0d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-bottom-hover.kb-gallery-id-736_2fd7fb-0d .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:linear-gradient(0deg, rgba(0, 0, 0, 0.8) 0, rgba(0, 0, 0, 0) 100%);}<\/style><div class=\"kb-gallery-wrap-id-736_2fd7fb-0d alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-736_2fd7fb-0d kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-scaled.jpg\" data-id=\"1515\" class=\"wp-image-1515\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-scaled.jpg\" data-id=\"1518\" class=\"wp-image-1518\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Vinicunca, Peru.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg\" data-id=\"1668\" class=\"wp-image-1668\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg\" data-id=\"1519\" class=\"wp-image-1519\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Vinicunca, Peru.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled.jpg\" data-id=\"1513\" class=\"wp-image-1513\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Waerebo, Indonesia.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg\" data-id=\"1520\" class=\"wp-image-1520\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Cusco, Peru.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled.jpg\" data-id=\"1517\" class=\"wp-image-1517\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Angkor Wat, Cambodia.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-scaled.jpg\" data-id=\"1618\" class=\"wp-image-1618\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Chiang Mai, Thailand.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg\" data-id=\"1516\" class=\"wp-image-1516\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-scaled.jpg\" data-id=\"1521\" class=\"wp-image-1521\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled.jpg\" class=\"kb-gallery-item-link\"  ><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled.jpg\" data-id=\"1512\" class=\"wp-image-1512\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Waerebo, Indonesia.<\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id736_a6147f-d5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id736_a6147f-d5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id736_a6147f-d5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id736_a6147f-d5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (min-width: 1025px){.kb-row-layout-id736_a6147f-d5{display:none !important;}}@media all and (max-width: 1024px){.kb-row-layout-id736_a6147f-d5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id736_a6147f-d5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id736_a6147f-d5 alignnone kb-v-lg-hidden wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column736_a74628-f6 > .kt-inside-inner-col,.kadence-column736_a74628-f6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column736_a74628-f6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column736_a74628-f6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column736_a74628-f6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column736_a74628-f6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column736_a74628-f6{position:relative;}@media all and (max-width: 1024px){.kadence-column736_a74628-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column736_a74628-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column736_a74628-f6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-736_24f2a6-2f{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-736_24f2a6-2f .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-736_24f2a6-2f .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-736_24f2a6-2f .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-caption-style-bottom.kb-gallery-id-736_24f2a6-2f .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-bottom-hover.kb-gallery-id-736_24f2a6-2f .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:linear-gradient(0deg, rgba(0, 0, 0, 0.8) 0, rgba(0, 0, 0, 0) 100%);}<\/style><div class=\"kb-gallery-wrap-id-736_24f2a6-2f alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-736_24f2a6-2f kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8551-scaled.jpg\" data-id=\"1515\" class=\"wp-image-1515\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7053-scaled.jpg\" data-id=\"1518\" class=\"wp-image-1518\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Vinicunca, Peru.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg\" data-id=\"1668\" class=\"wp-image-1668\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC9044-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg\" data-id=\"1519\" class=\"wp-image-1519\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7117-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Vinicunca, Peru.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled.jpg\" data-id=\"1513\" class=\"wp-image-1513\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4713-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Waerebo, Indonesia.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg\" data-id=\"1520\" class=\"wp-image-1520\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC7337-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Cusco, Peru.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled.jpg\" data-id=\"1517\" class=\"wp-image-1517\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC1475-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Angkor Wat, Cambodia.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC3142-scaled.jpg\" data-id=\"1618\" class=\"wp-image-1618\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Chiang Mai, Thailand.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:683px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:149%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-683x1024.jpg\" width=\"683\" height=\"1024\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg\" data-id=\"1516\" class=\"wp-image-1516\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-683x1024.jpg 683w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled-800x1200.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-200x300.jpg 200w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-768x1152.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-1024x1536.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-1365x2048.jpg 1365w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-8x12.jpg 8w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8552-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC8134-scaled.jpg\" data-id=\"1521\" class=\"wp-image-1521\"\/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Hoi An, Vietnam.<\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-has-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:1024px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1024x683.jpg\" width=\"1024\" height=\"683\" alt=\"\" data-full-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled.jpg\" data-light-image=\"http:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled.jpg\" data-id=\"1512\" class=\"wp-image-1512\" srcset=\"https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1024x683.jpg 1024w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-scaled-800x533.jpg 800w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-300x200.jpg 300w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-768x512.jpg 768w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-1536x1024.jpg 1536w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-2048x1365.jpg 2048w, https:\/\/mariolealphoto.com\/wp-content\/uploads\/2024\/03\/DSC4700-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Waerebo, Indonesia.<\/div><\/div><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-736","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/pages\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":13,"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/pages\/736\/revisions"}],"predecessor-version":[{"id":1683,"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/pages\/736\/revisions\/1683"}],"wp:attachment":[{"href":"https:\/\/mariolealphoto.com\/es\/wp-json\/wp\/v2\/media?parent=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}